{"id":13021,"date":"2018-12-05T16:19:21","date_gmt":"2018-12-05T15:19:21","guid":{"rendered":"http:\/\/www.icsiniscola2.edu.it\/?p=13021"},"modified":"2018-12-05T16:19:21","modified_gmt":"2018-12-05T15:19:21","slug":"progetto-di-educazione-alimentare-3a-latte-arborea","status":"publish","type":"post","link":"https:\/\/www.icsiniscola2.edu.it\/progetto-di-educazione-alimentare-3a-latte-arborea\/","title":{"rendered":"Progetto di educazione alimentare &#8211; 3A latte Arborea"},"content":{"rendered":"<p><a href=\"http:\/\/www.icsiniscola2.edu.it\/wp-content\/uploads\/2018\/12\/fwdprogettoeducazionealimentare3alattearborea.zip\"><div class=\"attachments\"><dl class=\"attachments attachments-large\"><dt class=\"icon\">\r\n\t<a title=\"fwdprogettoeducazionealimentare3alattearborea\" href=\"https:\/\/www.icsiniscola2.edu.it\/progetto-di-educazione-alimentare-3a-latte-arborea\/?aid=13022&sa=0\" >\r\n\t\t<img src=\"https:\/\/www.icsiniscola2.edu.it\/wp-content\/plugins\/eg-attachments\/img\/flags\/archive.png\" width=\"48\" height=\"48\"  alt=\"fwdprogettoeducazionealimentare3alattearborea\" \/>\r\n\t<\/a>\r\n<\/dt>\r\n<dd class=\"caption\">\r\n\t<strong>Titolo<\/strong>: <a title=\"fwdprogettoeducazionealimentare3alattearborea\" href=\"https:\/\/www.icsiniscola2.edu.it\/progetto-di-educazione-alimentare-3a-latte-arborea\/?aid=13022&sa=0\" >fwdprogettoeducazionealimentare3alattearborea<\/a> (0 click)\r\n\t<br\/>\r\n\t<strong>Etichetta<\/strong>: \r\n\t<br\/>\r\n\t<strong>Filename<\/strong>: fwdprogettoeducazionealimentare3alattearborea.zip\r\n\t<br\/>\r\n\t<strong>Dimensione<\/strong>: 3 MB\r\n<\/dd>\r\n<\/dl><p><\/p><\/div><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incontro da calendarizzare in 8 classi della scuola primaria nel mese di febbraio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13021"}],"collection":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/comments?post=13021"}],"version-history":[{"count":1,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13021\/revisions"}],"predecessor-version":[{"id":13023,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13021\/revisions\/13023"}],"wp:attachment":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/media?parent=13021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/categories?post=13021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/tags?post=13021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}