{"id":13607,"date":"2019-04-01T13:28:00","date_gmt":"2019-04-01T11:28:00","guid":{"rendered":"http:\/\/www.icsiniscola2.edu.it\/?p=13607"},"modified":"2019-04-01T16:35:03","modified_gmt":"2019-04-01T14:35:03","slug":"biblioteca-comunale-dialoghi-con-lautore","status":"publish","type":"post","link":"https:\/\/www.icsiniscola2.edu.it\/biblioteca-comunale-dialoghi-con-lautore\/","title":{"rendered":"Biblioteca Comunale &#8211; Dialoghi con l&#8217;autore"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-13608\" src=\"http:\/\/www.icsiniscola2.edu.it\/wp-content\/uploads\/2019\/04\/locandina-Dialoghi-213x300.jpg\" alt=\"\" width=\"213\" height=\"300\" srcset=\"https:\/\/www.icsiniscola2.edu.it\/wp-content\/uploads\/2019\/04\/locandina-Dialoghi-213x300.jpg 213w, https:\/\/www.icsiniscola2.edu.it\/wp-content\/uploads\/2019\/04\/locandina-Dialoghi-768x1080.jpg 768w, https:\/\/www.icsiniscola2.edu.it\/wp-content\/uploads\/2019\/04\/locandina-Dialoghi-728x1024.jpg 728w, https:\/\/www.icsiniscola2.edu.it\/wp-content\/uploads\/2019\/04\/locandina-Dialoghi-180x253.jpg 180w, https:\/\/www.icsiniscola2.edu.it\/wp-content\/uploads\/2019\/04\/locandina-Dialoghi.jpg 945w\" sizes=\"(max-width: 213px) 100vw, 213px\" \/><\/p>\n<p>link della pagina dell&#8217;autore: <a href=\"http:\/\/www.paolomontaldo.com\/\">http:\/\/www.paolomontaldo.com<\/a>\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dialoghi con l&#8217;Autore: Paolo Montaldo &#8211; Venerd\u00ec 5 Aprile 2019 ore 18,00 -Biblioteca Comunale presso Ex casello &#8211; La Caletta di Siniscola <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13607"}],"collection":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/comments?post=13607"}],"version-history":[{"count":2,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13607\/revisions"}],"predecessor-version":[{"id":13617,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13607\/revisions\/13617"}],"wp:attachment":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/media?parent=13607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/categories?post=13607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/tags?post=13607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}