{"id":13830,"date":"2019-05-18T15:49:01","date_gmt":"2019-05-18T13:49:01","guid":{"rendered":"http:\/\/www.icsiniscola2.edu.it\/?p=13830"},"modified":"2019-05-18T15:49:01","modified_gmt":"2019-05-18T13:49:01","slug":"avviso-di-selezione-per-n-6-unita-di-personale-appartenenti-al-ruolo-di-dirigente-scolastico-o-docente","status":"publish","type":"post","link":"https:\/\/www.icsiniscola2.edu.it\/avviso-di-selezione-per-n-6-unita-di-personale-appartenenti-al-ruolo-di-dirigente-scolastico-o-docente\/","title":{"rendered":"Avviso di selezione per n. 6 unit\u00e0 di personale, appartenenti al ruolo di Dirigente scolastico o Docente"},"content":{"rendered":"<p><a href=\"http:\/\/www.icsiniscola2.edu.it\/wp-content\/uploads\/2019\/05\/iavvisodiselezionepern_6seiunitdipersonaleap.zip\"><div class=\"attachments\"><dl class=\"attachments attachments-large\"><dt class=\"icon\">\r\n\t<a title=\"iavvisodiselezionepern_6seiunitdipersonaleap\" href=\"https:\/\/www.icsiniscola2.edu.it\/avviso-di-selezione-per-n-6-unita-di-personale-appartenenti-al-ruolo-di-dirigente-scolastico-o-docente\/?aid=13831&sa=0\" >\r\n\t\t<img src=\"https:\/\/www.icsiniscola2.edu.it\/wp-content\/plugins\/eg-attachments\/img\/flags\/archive.png\" width=\"48\" height=\"48\"  alt=\"iavvisodiselezionepern_6seiunitdipersonaleap\" \/>\r\n\t<\/a>\r\n<\/dt>\r\n<dd class=\"caption\">\r\n\t<strong>Titolo<\/strong>: <a title=\"iavvisodiselezionepern_6seiunitdipersonaleap\" href=\"https:\/\/www.icsiniscola2.edu.it\/avviso-di-selezione-per-n-6-unita-di-personale-appartenenti-al-ruolo-di-dirigente-scolastico-o-docente\/?aid=13831&sa=0\" >iavvisodiselezionepern_6seiunitdipersonaleap<\/a> (0 click)\r\n\t<br\/>\r\n\t<strong>Etichetta<\/strong>: \r\n\t<br\/>\r\n\t<strong>Filename<\/strong>: iavvisodiselezionepern_6seiunitdipersonaleap.zip\r\n\t<br\/>\r\n\t<strong>Dimensione<\/strong>: 437 KB\r\n<\/dd>\r\n<\/dl><p><\/p><\/div><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utilizzazione per il triennio 2019\/2020 \u2013 2021\/2022 presso gli Uffici di supporto del Dipartimento per la programmazione e la gestione delle risorse umane, finanziarie per lo svolgimento di compiti connessi con l\u2019attuazione dell\u2019autonomia ai sensi dell\u2019articolo 26, comma 8, della Legge 23.12.1998, n. 448. Decorrenza 01.09.2019.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13830"}],"collection":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/comments?post=13830"}],"version-history":[{"count":1,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13830\/revisions"}],"predecessor-version":[{"id":13832,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/posts\/13830\/revisions\/13832"}],"wp:attachment":[{"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/media?parent=13830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/categories?post=13830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icsiniscola2.edu.it\/wp-json\/wp\/v2\/tags?post=13830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}